{"id":7931,"date":"2024-02-16T10:37:54","date_gmt":"2024-02-16T09:37:54","guid":{"rendered":"https:\/\/lesantonies.com\/avis-legal\/"},"modified":"2024-03-14T13:34:38","modified_gmt":"2024-03-14T12:34:38","slug":"avis-legal","status":"publish","type":"page","link":"https:\/\/lesantonies.com\/es\/avis-legal\/","title":{"rendered":"Aviso Legal"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7931\" class=\"elementor elementor-7931 elementor-7634\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-69911fc elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"69911fc\" data-element_type=\"section\" id=\"nosaltres\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a21c82f\" data-id=\"a21c82f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a259c1 elementor-widget elementor-widget-heading\" data-id=\"1a259c1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 26-03-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Aviso legal<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-193ba74 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"193ba74\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 26-03-2024 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#0c0d0e;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-block-end:0;flex-grow:1;border-block-start:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider--element-align-start .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-start .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-start .elementor-divider__element{margin-inline-start:0}.elementor-widget-divider--element-align-end .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-end .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-end .elementor-divider__element{margin-inline-end:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-block-start:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-con-inner>.elementor-widget-divider,.e-con>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5c773b elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"a5c773b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 26-03-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<h2 style=\"text-align: center;\">AVISO LEGAL<\/h2>\n<ol>\n<li>OBJETO<\/li>\n<\/ol>\n<p>El presente aviso legal regula el uso y utilizaci\u00f3n del sitio web <a href=\"http:\/\/www.lesantonies.com\">www.lesantonies.com<\/a>, del que es titular ANTONIES ON FIRE, SLU (en adelante, EL PROPIETARIO DE LA WEB).<\/p>\n<p>La navegaci\u00f3n por el sitio web de EL PROPIETARIO DE LA WEB le atribuye la condici\u00f3n de USUARIO del mismo y conlleva su aceptaci\u00f3n plena y sin reservas de todas y cada una de las condiciones publicadas en este aviso legal, advirtiendo de que dichas condiciones podr\u00e1n ser modificadas sin notificaci\u00f3n previa por parte de EL PROPIETARIO DE LA WEB, en cuyo caso se proceder\u00e1 a su publicaci\u00f3n y aviso con la m\u00e1xima antelaci\u00f3n posible.<\/p>\n<p>Por ello es recomendable leer atentamente su contenido en caso de desear acceder y hacer uso de la informaci\u00f3n y de los servicios ofrecidos desde este sitio web.<\/p>\n<p>El usuario, adem\u00e1s, se obliga a hacer un uso correcto del sitio web de conformidad con las leyes, la buena fe, el orden p\u00fablico, los usos del tr\u00e1fico y el presente Aviso Legal, y responder\u00e1 frente a EL PROPIETARIO DE LA WEB o frente a terceros, de cualesquiera da\u00f1os y perjuicios que pudieran causarse como consecuencia del incumplimiento de dicha obligaci\u00f3n.<\/p>\n<p>Cualquier utilizaci\u00f3n distinta a la autorizada est\u00e1 expresamente prohibida, pudiendo EL PROPIETARIO DE LA WEB denegar o retirar el acceso y su uso en cualquier momento.<\/p>\n<ol start=\"2\">\n<li>IDENTIFICACI\u00d3N<\/li>\n<\/ol>\n<p>EL PROPIETARIO DE LA WEB, en cumplimiento de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico, le informa de que:<\/p>\n<ul>\n<li>Su denominaci\u00f3n social es: ANTONIES ON FIRE, SLU<\/li>\n<li>Su CIF es: B72929037<\/li>\n<li>Su domicilio social est\u00e1 en: PORT BAL\u00cdS LOCALS 24-25-26 &#8211; 08392 &#8211; SANT ANDREU DE LLAVANERES \u2013 BARCELONA<\/li>\n<li>Inscrita en el Registro Mercantil de Barcelona. Tomo 48610, Folio 15, Secci\u00f3n 8, Hoja 589942, Inscripci\u00f3n 1.<\/li>\n<\/ul>\n<ol start=\"3\">\n<li>COMUNICACIONES<\/li>\n<\/ol>\n<p>Para comunicarse con nosotros, ponemos a su disposici\u00f3n diferentes medios de contacto que detallamos a continuaci\u00f3n:<\/p>\n<ul>\n<li>: 937 92 86 13<\/li>\n<li>Email: <a href=\"mailto:info@lesantonies.com\">info@lesantonies.com<\/a><\/li>\n<\/ul>\n<p>Todas las notificaciones y comunicaciones entre los usuarios y PROPIETARIO DE LA WEB se considerar\u00e1n eficaces, a todos los efectos, cuando se realicen a trav\u00e9s de cualquier medio de los detallados anteriormente.<\/p>\n<ol start=\"4\">\n<li>CONDICIONES DE ACCESO Y UTILIZACI\u00d3N<\/li>\n<\/ol>\n<p>El sitio web y sus servicios son de acceso libre y gratuito. No obstante, PROPIETARIO DE LA WEB puede condicionar la utilizaci\u00f3n de algunos de los servicios ofrecidos en su web a la previa cumplimentaci\u00f3n del correspondiente formulario.<\/p>\n<p>El usuario garantiza la autenticidad y actualidad de todos aquellos datos que comunique a PROPIETARIO DE LA WEB y ser\u00e1 el \u00fanico responsable de las manifestaciones falsas o inexactas que realice.<\/p>\n<p>El usuario se compromete expresamente a hacer un uso adecuado de los contenidos y servicios de PROPIETARIO DE LA WEB y a no emplearlos para, entre otros:<\/p>\n<ol>\n<li>Difundir contenidos delictivos, violentos, pornogr\u00e1ficos, racistas, xen\u00f3fobos, ofensivos, de apolog\u00eda del terrorismo o, en general, contrarios a la ley o al orden p\u00fablico.<\/li>\n<li>Introducir en la red virus inform\u00e1ticos o realizar actuaciones susceptibles de alterar, estropear, interrumpir o generar errores o da\u00f1os en los documentos electr\u00f3nicos, datos o sistemas f\u00edsicos y l\u00f3gicos de PROPIETARIO DE LA WEB o de terceras personas; as\u00ed como obstaculizar el acceso de otros usuarios al sitio web y a sus servicios mediante el consumo masivo de los recursos inform\u00e1ticos a trav\u00e9s de los cuales PROPIETARIO DE LA WEB presta sus servicios.<\/li>\n<li>Intentar acceder a las cuentas de correo electr\u00f3nico de otros usuarios o a \u00e1reas restringidas de los sistemas inform\u00e1ticos de PROPIETARIO DE LA WEB o de terceros y, en su caso, extraer informaci\u00f3n.<\/li>\n<li>Vulnerar los derechos de propiedad intelectual o industrial, as\u00ed como violar la confidencialidad de la informaci\u00f3n de PROPIETARIO DE LA WEB o de terceros.<\/li>\n<li>Suplantar la identidad de cualquier otro usuario.<\/li>\n<li>Reproducir, copiar, distribuir, poner a disposici\u00f3n de, o cualquier otra forma de comunicaci\u00f3n p\u00fablica, transformar o modificar los contenidos, a menos que se cuente con la autorizaci\u00f3n del titular de los correspondientes derechos o ello resulte legalmente permitido.<\/li>\n<li>Recabar datos con finalidad publicitaria y de remitir publicidad de cualquier clase y comunicaciones con fines de venta u otras de naturaleza comercial sin que medie su previa solicitud o consentimiento.<\/li>\n<\/ol>\n<p>Todos los contenidos del sitio web, como textos, fotograf\u00edas, gr\u00e1ficos, im\u00e1genes, iconos, tecnolog\u00eda, software, as\u00ed como su dise\u00f1o gr\u00e1fico y c\u00f3digos fuente, constituyen una obra cuya propiedad pertenece a PROPIETARIO DE LA WEB, sin que puedan entenderse cedidos al usuario ninguno de los derechos de explotaci\u00f3n sobre los mismos m\u00e1s all\u00e1 de lo estrictamente necesario para el correcto uso de la web.<\/p>\n<p>En definitiva, los usuarios que accedan a este sitio web pueden visualizar los contenidos y efectuar, en su caso, copias privadas autorizadas siempre que los elementos reproducidos no sean cedidos posteriormente a terceros, ni se instalen a servidores conectados a redes, ni sean objeto de ning\u00fan tipo de explotaci\u00f3n.<\/p>\n<p>Asimismo, todas las marcas, nombres comerciales o signos distintivos de cualquier clase que aparecen en el sitio web son propiedad de PROPIETARIO DE LA WEB, sin que pueda entenderse que el uso o acceso al mismo atribuya al usuario derecho alguno sobre los mismos.<\/p>\n<p>La distribuci\u00f3n, modificaci\u00f3n, cesi\u00f3n o comunicaci\u00f3n p\u00fablica de los contenidos y cualquier otro acto que no haya sido expresamente autorizado por el titular de los derechos de explotaci\u00f3n quedan prohibidos.<\/p>\n<p>El establecimiento de un hiperenlace no implica en ning\u00fan caso la existencia de relaciones entre PROPIETARIO DE LA WEB y el propietario del sitio web en la que se establezca, ni la aceptaci\u00f3n y aprobaci\u00f3n por parte de PROPIETARIO DE LA WEB de sus contenidos o servicios.<\/p>\n<p>PROPIETARIO DE LA WEB no se responsabiliza del uso que cada usuario les d\u00e9 a los materiales puestos a disposici\u00f3n en este sitio web ni de las actuaciones que realice en base a los mismos.<\/p>\n<ul>\n<li>\n<h5><em>EXCLUSI\u00d3N DE GARANT\u00cdAS Y DE RESPONSABILIDAD EN EL ACCESO Y LA UTILIZACI\u00d3N<\/em><\/h5>\n<\/li>\n<\/ul>\n<p>El contenido del presente sitio web es de car\u00e1cter general y tiene una finalidad meramente informativa, sin que se garantice plenamente el acceso a todos los contenidos, ni su exhaustividad, correcci\u00f3n, vigencia o actualidad, ni su idoneidad o utilidad para un objetivo espec\u00edfico.<\/p>\n<p>PROPIETARIO DE LA WEB excluye, hasta donde permite el ordenamiento jur\u00eddico, cualquier responsabilidad por los da\u00f1os y perjuicios de toda naturaleza derivados de:<\/p>\n<ol>\n<li>La imposibilidad de acceso al sitio web o la falta de veracidad, exactitud, exhaustividad y\/o actualidad de los contenidos, as\u00ed como la existencia de vicios y defectos de toda clase de los contenidos transmitidos, difundidos, almacenados, puestos a disposici\u00f3n, a los que se haya accedido a trav\u00e9s del sitio web o de los servicios que se ofrecen.<\/li>\n<li>La presencia de virus o de otros elementos en los contenidos que puedan producir alteraciones en los sistemas inform\u00e1ticos, documentos electr\u00f3nicos o datos de los usuarios.<\/li>\n<li>El incumplimiento de las leyes, la buena fe, el orden p\u00fablico, los usos del tr\u00e1fico y el presente aviso legal como consecuencia del uso incorrecto del sitio web. En particular, y a modo ejemplificativo, PROPIETARIO DE LA WEB no se hace responsable de las actuaciones de terceros que vulneren derechos de propiedad intelectual e industrial, secretos empresariales, derechos al honor, a la intimidad personal y familiar y a la propia imagen, as\u00ed como la normativa en materia de competencia desleal y publicidad il\u00edcita.<\/li>\n<\/ol>\n<p>Asimismo, PROPIETARIO DE LA WEB declina cualquier responsabilidad respecto a la informaci\u00f3n que se halle fuera de esta web y no sea gestionada directamente por nuestro webmaster. La funci\u00f3n de los links que aparecen en esta web es exclusivamente la de informar al usuario sobre la existencia de otras fuentes susceptibles de ampliar los contenidos que ofrece este sitio web. PROPIETARIO DE LA WEB no garantiza ni se responsabiliza del funcionamiento o accesibilidad de los sitios enlazados; ni sugiere, invita o recomienda la visita a los mismos, por lo que tampoco ser\u00e1 responsable del resultado obtenido. PROPIETARIO DE LA WEB no se responsabiliza del establecimiento de hiperv\u00ednculos por parte de terceros.<\/p>\n<ul>\n<li>\n<h5><em>PROCEDIMIENTO EN CASO DE REALIZACI\u00d3N DE ACTIVIDADES DE CAR\u00c1CTER IL\u00cdCITO<\/em><\/h5>\n<\/li>\n<\/ul>\n<p>En el caso de que cualquier usuario o un tercero considere que existen hechos o circunstancias que revelen el car\u00e1cter il\u00edcito de la utilizaci\u00f3n de cualquier contenido y\/o de la realizaci\u00f3n de cualquier actividad en las p\u00e1ginas web incluidas o accesibles a trav\u00e9s del sitio web, deber\u00e1 enviar una notificaci\u00f3n a PROPIETARIO DE LA WEB identific\u00e1ndose debidamente y especificando las supuestas infracciones.<\/p>\n<ul>\n<li>\n<h5><em>PUBLICACIONES<\/em><\/h5>\n<\/li>\n<\/ul>\n<p>La informaci\u00f3n administrativa facilitada a trav\u00e9s del sitio web no sustituye la publicidad legal de las leyes, normativas, planes, disposiciones generales y actos que tengan que ser publicados formalmente a los diarios oficiales de las administraciones p\u00fablicas, que constituyen el \u00fanico instrumento que da fe de su autenticidad y contenido. La informaci\u00f3n disponible en este sitio web debe entenderse como una gu\u00eda sin prop\u00f3sito de validez legal.<\/p>\n<ol start=\"5\">\n<li>LEGISLACI\u00d3N APLICABLE<\/li>\n<\/ol>\n<p>Las condiciones presentes se regir\u00e1n por la legislaci\u00f3n espa\u00f1ola vigente.<\/p>\n<p>La lengua utilizada ser\u00e1 el Castellano.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Aviso legal AVISO LEGAL OBJETO El presente aviso legal regula el uso y utilizaci\u00f3n del sitio web www.lesantonies.com, del que es titular ANTONIES ON FIRE, SLU (en adelante, EL PROPIETARIO DE LA WEB). La navegaci\u00f3n por el sitio web de EL PROPIETARIO DE LA WEB le atribuye la condici\u00f3n de USUARIO del mismo y conlleva&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/lesantonies.com\/es\/wp-json\/wp\/v2\/pages\/7931"}],"collection":[{"href":"https:\/\/lesantonies.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lesantonies.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lesantonies.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lesantonies.com\/es\/wp-json\/wp\/v2\/comments?post=7931"}],"version-history":[{"count":6,"href":"https:\/\/lesantonies.com\/es\/wp-json\/wp\/v2\/pages\/7931\/revisions"}],"predecessor-version":[{"id":8018,"href":"https:\/\/lesantonies.com\/es\/wp-json\/wp\/v2\/pages\/7931\/revisions\/8018"}],"wp:attachment":[{"href":"https:\/\/lesantonies.com\/es\/wp-json\/wp\/v2\/media?parent=7931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}